{"id":1434,"date":"2022-04-18T07:00:59","date_gmt":"2022-04-18T05:00:59","guid":{"rendered":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/?p=1434"},"modified":"2024-08-21T16:50:57","modified_gmt":"2024-08-21T14:50:57","slug":"la-cornucopia-de-las-posibilidades","status":"publish","type":"post","link":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/","title":{"rendered":"La cornucopia de las posibilidades"},"content":{"rendered":"<p>Llevo a\u00f1os siguiendo a distancia las muchas formas en las que aparece el sistema educativo en los medios. Alguien deber\u00eda hacer un estudio de c\u00f3mo lo hemos convertido en un pozo de obligaciones (imposibles). Todo lo queremos arreglar echando mano de los colegios. Todos los d\u00e9ficit, carencias, conflictos, ambig\u00fcedades y contradicciones de nuestro mundo deben repararse desde la escuela. Ning\u00fan republicanismo es respetable si no reconfirma en cada gesto a la escuela como el motor del cambio.<\/p>\n<p>Si hay violencia de g\u00e9nero tenemos que trabajar con los escolares. Si la memoria hist\u00f3rica nos divide echamos manos del aula. Si tenemos problemas con los residuos s\u00f3lidos, la movilidad urbana, la seguridad vial, el acoso en internet, la salud mental, la vida sexual o la calidad alimentaria, la soluci\u00f3n siempre incluye nuevas tareas para nuestros profes. Seguro que les abrumamos por las mil formas abstractas de evocarlos. No se si les halaga o deprime esta ret\u00f3rica que en apariencia convierte la educaci\u00f3n en el santo grial de la vida p\u00fablica.<\/p>\n<p>Es imposible estar en desacuerdo con estas recetas de urgencia, pero creo que hace ya mucho tiempo que los maestros se volvieron sordos y no escuchan a tanto profeta del todo a cien. Tenemos diagn\u00f3sticos que provienen de todas partes, y tambi\u00e9n las mayores sospechas sobre quienes aconsejan al margen de las demandas de los trabajadores de la ense\u00f1anza. Y no me refiero a quienes gestionan, sino a quienes est\u00e1n a pie de aula. Las gentes de la pol\u00edtica, la religi\u00f3n, el deporte, la seguridad o la sanidad, juntos y por separado, tienen planes que les involucran: son planificadores estrat\u00e9gicos, pero nunca afectivos. Dise\u00f1an sin escuchar.<\/p>\n<p>A nadie sorprende que la gente est\u00e9 saturada por este doble movimiento que, de un lado, ve la escuela como el epicentro de todo lo que importa mientras que, por el otro, nadie parece escuchar sus necesidades. No es un problema nuevo, ni tiene f\u00e1cil soluci\u00f3n. Pero ciertamente podemos intentar otra estrategia y decir algo que trate de ponerse del lado de los profes y ensanche las posibilidades de los estudiantes, en lugar de enfatizar la necesidad de nuevos decretos y m\u00e1s obligaciones.<\/p>\n<p>Hay muchos proyectos, nacidos desde dentro del aula, emprendidos por profes que saben tomar partido por sus alumnos y que saben que la escuela, lejos de ser un problema, es la soluci\u00f3n, siempre que se les deje hacer y que se les eval\u00fae menos y se les valore m\u00e1s. Valorarlos implica darles agencia, dotarlos con herramientas para que, seg\u00fan las circunstancias, puedan elegir la m\u00e1s adecuada y desplegar sus habilidades.<\/p>\n<p>Apoyar a los profes siempre fue parte del compromiso que adoptamos en el proyecto de <a href=\"http:\/\/laaventuradeaprender.intef.es\/proyecto\">Gu\u00edas LADA<\/a> del que modestamente queremos describir aqu\u00ed. Contar con los profes siempre fue importante, pero nuestra verdadera motivaci\u00f3n eran los alumnos. Part\u00edamos de la convicci\u00f3n de que ambos, unos y otros, merec\u00edan ser considerados agentes productores de conocimiento siempre que logr\u00e1semos poner a su disposici\u00f3n los instrumentos adecuados.<\/p>\n<p>No es verdad ni imprescindible que la escuela solo pueda ser una instancia de transmisi\u00f3n del saber. Lo es. No vamos a discutirlo. Pero hay muchas maneras de imaginar lo que ocurre en el aula y, la menos estimulante es la que se conforma con visualizar un espacio cerrado donde uno habla y los dem\u00e1s escuchan. Hay m\u00e1s posibilidades y cada grupo debe explorarlas. \u00a0Nosotros pensamos que la clave est\u00e1 en proporcionar un repertorio amplio de herramientas que les animen a trabajar en equipo, sumar habilidades, repartirse tareas y, sobre todo, que les ayuden a auto imaginarse como productores: gente que crea o, en otras palabras, que da vida a cosas que antes no exist\u00edan.<\/p>\n<p>La cultura en el aula, insistimos, tambi\u00e9n puede ser una cultura de producci\u00f3n. En este sentido la distancia entre lo que sucede en los institutos y en los centros de formaci\u00f3n profesional no deber\u00eda ser tan grande. En ambos espacios se puede aprender haciendo. Por supuesto, no vamos ahora a desdecirnos y emprender la ya criticada deriva de asignar nuevas tareas a quien se deje.\u00a0 Estamos hablando de posibilidades al alcance de la mano y, por tanto, de gestos tan voluntarios como cercanos. La idea es que las herramientas est\u00e9n disponibles y que cada quien las use si las necesita.<\/p>\n<p>Lo m\u00e1s singular en La Aventura de Aprender (LADA) ha sido la elecci\u00f3n del lugar de procedencia de las herramientas que difunde. Como quer\u00edamos acercar, en la medida de lo posible, el mundo de la escuela a su entorno, tratamos de escuchar el murmullo de lo que se hablaba en la calle. Quer\u00edamos dialogar con todo eso de lo que hablan los padres y las madres, los trabajadores y trabajadoras, y, en fin, los vecinos y vecinas. Nuestra convicci\u00f3n es que cuanto m\u00e1s nos acerquemos a <a href=\"https:\/\/www.youtube.com\/watch?v=wAY54kOWPJQ\">lo que (nos) pasa<\/a>, m\u00e1s f\u00e1cil ser\u00e1 captar la atenci\u00f3n de quienes participen.<\/p>\n<p>Y si de verdad queremos dejarnos afectar por toda la energ\u00eda que hace vibrar a nuestras ciudades, lo mejor es escuchar las cosas que movilizan los colectivos ciudadanos, las comunidades de afectados y, en general, los movimientos sociales. Todos estos grupos tienen en com\u00fan la seguridad de que hay alg\u00fan asunto de la incumbencia general y que merece mayor atenci\u00f3n p\u00fablica. Se trata de colectivos abiertos que funcionan como sensores de alerta temprana de problemas por venir y que nos recuerdan la urgencia de reaccionar a tiempo.<\/p>\n<p>Adem\u00e1s de agentes pol\u00edticos, tambi\u00e9n son agentes cognitivos en la medida en la que se hacen preguntas que consideran desatendidas y, en consecuencia, obtienen tambi\u00e9n otras respuestas. No es que nieguen los hechos, sino que discuten las prioridades y nos invitan a situar el foco en otros asuntos. Proponen preguntas diferentes. Sus respuestas se obtienen mediante procedimientos m\u00e1s precarios de lo habitual en la academia y, en consecuencia, no tiene la misma precisi\u00f3n. Es verdad que sus propuestas pueden ser menos fiables, pero eso no las convierte en desde\u00f1ables. Nos muestran la necesidad de considerar alternativas, incorporar sensibilidades, escuchar discrepancias e integrar la diversidad que somos. As\u00ed es como funciona la democracia y as\u00ed es como hacemos habitable nuestro mundo.<\/p>\n<figure id=\"attachment_1443\" aria-describedby=\"caption-attachment-1443\" style=\"width: 470px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/proyectos-colaborativos\" target=\"_blank\" rel=\"noopener\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-1443\" src=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/28\/2022\/04\/Guias_LADA-2-598x1024.jpeg\" alt=\"Portada de las \u00faltimas gu\u00edas LADA publicadas\" width=\"470\" height=\"805\" srcset=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2-598x1024.jpeg 598w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2-175x300.jpeg 175w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2-768x1316.jpeg 768w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2-150x257.jpeg 150w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2-450x771.jpeg 450w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/Guias_LADA-2.jpeg 880w\" sizes=\"(max-width: 470px) 100vw, 470px\" \/><\/a><figcaption id=\"caption-attachment-1443\" class=\"wp-caption-text\">Portada de las \u00faltimas gu\u00edas LADA publicadas<\/figcaption><\/figure>\n<p>Pero hablemos un poco de los m\u00e9todos utilizados por estos grupos, pues cuando antes los califiqu\u00e9 de precarios mi intenci\u00f3n no era descalificarlos, sino justo lo contrario: mostrar que, a veces, con muy poco se puede hacer mucho. Quer\u00eda abrir una conversaci\u00f3n sobre qu\u00e9 pr\u00e1cticas, protocolos o herramientas llevar al aula. Trasladar al colegio las utilizadas por los activistas podr\u00eda tener dos ventajas: una, su bajo coste en t\u00e9rminos de dinero y de tiempo de aprendizaje y, dos, su vinculaci\u00f3n real con problemas concretos abordados por personas del com\u00fan, es decir, sin mucha formaci\u00f3n, sin mucho tiempo y sin mucha homogeneidad. Justo lo que necesitamos, pues tampoco en nuestros colegios la situaci\u00f3n es boyante.<\/p>\n<p>Lo que cada Gu\u00eda LADA ofrece es una receta para aprender una herramienta que ha probado ser eficaz en los mundos del activismo. Las hay de todo tipo y pronto habr\u00e1 m\u00e1s. Lo ideal ser\u00eda que cada quien encuentre descrito el instrumento que necesita. Podemos aprender en muchas direcciones: desde c\u00f3mo hacer una <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/proyectos-colaborativos\/como-hacer-una-opera\">\u00f3pera<\/a>, un <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-hacer-un-fanzine\">fanzine<\/a> o una <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-hacer-un-fanzine\">performance<\/a> a c\u00f3mo montar un <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-hacer-un-banco-de-semillas\">banco de semillas<\/a>, Un <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-hacer-biohacking-genetico-\">laboratorio de biohacking<\/a> o un <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-hacer-un-espacio-maker\">espacio maker<\/a>. Con esas herramientas podemos adentrarnos en los mundos de la <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-investigar-\">experimentaci\u00f3n<\/a>, el <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-hacer-teatro-comunitario-\">teatro<\/a>, la <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-hacer-fietas-raras-\">fiesta<\/a> o las <a href=\"http:\/\/laaventuradeaprender.intef.es\/documents\/10184\/73911\/AlbertoCorsin_infraestructurasD.pdf\">infraestructuras<\/a>, como tambi\u00e9n dejarnos afectar por los <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-hacer-patrimonios-comunes-\">patrimonios rurales<\/a>, las <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/-como-hacer-inclusiva-tu-escuela-1\">pr\u00e1cticas inclusivas<\/a>, las <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/proyectos-colaborativos\/como-reconocer-inteligencias-colectivas\">inteligencias colectivas<\/a>, los <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-identificar-los-micromachismos\">micromachismos<\/a> o los <a href=\"http:\/\/laaventuradeaprender.intef.es\/guias\/como-hacer-un-banco-de-tiempo\">bancos de tiempo<\/a>. Insistimos: nos gusta imaginar LADA como una caja de herramientas nacidas entre quienes creen que otro mundo es posible y han transitado desde la protesta a la propuesta.<\/p>\n<blockquote><p>El pozo de las obligaciones puede convertirse en una cornucopia de posibilidades<\/p><\/blockquote>\n<p>Habiendo ya casi un centenar de Gu\u00edas disponibles, todas con una licencia <em>Creative Commons<\/em> que otorga a sus usuarios las mayores libertades imaginables, resulta imposible mencionarlas todas. Para facilitar un acercamiento a su naturaleza como proyecto, he preparado un mapa que nos ayude o visualizar la diversidad de instrumentos y prop\u00f3sitos para los que pueden ser utilizadas.<\/p>\n<figure id=\"attachment_1450\" aria-describedby=\"caption-attachment-1450\" style=\"width: 1024px\" class=\"wp-caption alignnone\"><img decoding=\"async\" class=\"wp-image-1450 size-large\" src=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/28\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-1024x598.jpeg\" alt=\"Mapa de herramientas o Gu\u00edas LADA ya publicadas. Elaboraci\u00f3n propia.\" width=\"1024\" height=\"598\" srcset=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-1024x598.jpeg 1024w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-300x175.jpeg 300w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-768x449.jpeg 768w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-150x88.jpeg 150w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2-450x263.jpeg 450w, https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/WhatsApp-Image-2022-04-18-at-11.43.39-AM-2.jpeg 1198w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption id=\"caption-attachment-1450\" class=\"wp-caption-text\">Mapa de herramientas o Gu\u00edas LADA ya publicadas. Elaboraci\u00f3n propia.<\/figcaption><\/figure>\n<p><span style=\"color: #ffffff\">.<\/span><br \/>\nEl pozo de las obligaciones puede convertirse en una cornucopia de posibilidades. Cierto, sabemos que los profes no tienen tiempo y que, con frecuencia, tienen el paso marcado. Le cuesta mucho salirse del rail y atreverse con experiencias diferentes. Lo sabemos. No es para recordarles nuevas obligaciones para lo que (les) escribimos. \u00a0Nuestra intenci\u00f3n es la contraria.\u00a0Quer\u00edamos que supieran que, si lo desean, pueden contar con una colecci\u00f3n de herramientas f\u00e1ciles, baratas y eficientes que les ayudar\u00e1n a hacer su clase m\u00e1s divertida para quienes participen y m\u00e1s atenta a lo que sucede en su entorno.<\/p>\n<p>El origen de la ciencia moderna est\u00e1 asociado al pozo en el que cay\u00f3 Thales porque, seg\u00fan cuenta la leyenda, estaba tan atento a las cosas del cielo que no ve\u00eda las del suelo. Y, justo all\u00ed, hab\u00eda una mujer que rompi\u00f3 a carcajadas viendo la estupidez de aquel sabio insensible a lo que suced\u00eda en su entorno. Esa ca\u00edda y esa risotada dan cuenta del desencuentro entre los sabios y los comunes, y nos recuerda la necesidad de imaginar otra relaci\u00f3n entre los que saben y los que no saben.\u00a0 Nuestro pozo de obligaciones ha sido cavado por un ej\u00e9rcito de <em>expertos capacitistas<\/em>, que convirtieron la acumulaci\u00f3n de capacidades y m\u00e9ritos en el fin de la escuela. Aqu\u00ed, en nuestro pozo, son los maestros quienes se mofan porque no entienden esa miner\u00eda del exceso, ese quererlos tanto, sin quererlos bien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Llevo a\u00f1os siguiendo a distancia las muchas formas en las que aparece el sistema educativo en los medios. Alguien deber\u00eda hacer un estudio de c\u00f3mo lo hemos convertido en un pozo de obligaciones (imposibles). Todo lo queremos arreglar echando mano de los colegios. Todos los d\u00e9ficit, carencias, conflictos, ambig\u00fcedades y contradicciones de nuestro mundo deben<\/p>\n","protected":false},"author":213,"featured_media":1438,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[59,55,54,25,20,36,17],"tipo":[96],"class_list":{"0":"post-1434","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-por-otra-politica-educativa","8":"tag-ciudadania","9":"tag-ciudades-educadoras","10":"tag-comunidades-profesionales-de-aprendizaje","11":"tag-curriculo-escolar","12":"tag-escuela-publica","13":"tag-justicia-social","14":"tag-politicas-educativas","15":"tipo-analisis"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla\" \/>\n<meta property=\"og:description\" content=\"Queremos acercar el mundo de la escuela a su entorno y tratamos de escuchar el murmullo de lo que se habla en la calle. Queremos dialogar con todo eso de lo que hablan los padres y las madres, los trabajadores y trabajadoras, y, en fin, los vecinos y vecinas. Nuestra convicci\u00f3n es que cuanto m\u00e1s nos acerquemos a lo que (nos) pasa, m\u00e1s f\u00e1cil ser\u00e1 captar la atenci\u00f3n de quienes participan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Por otra pol\u00edtica educativa. Foro de Sevilla.\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-18T05:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-21T14:50:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Lafuente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Lafuente\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/\"},\"author\":{\"name\":\"Antonio Lafuente\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/#\\\/schema\\\/person\\\/4ee42898eb46b1f67fefe730f1a5209b\"},\"headline\":\"La cornucopia de las posibilidades\",\"datePublished\":\"2022-04-18T05:00:59+00:00\",\"dateModified\":\"2024-08-21T14:50:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/\"},\"wordCount\":1717,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2022\\\/04\\\/277591728_1177711622966687_2407132596885224980_n.jpg\",\"keywords\":[\"Ciudadan\u00eda\",\"ciudades educadoras\",\"Comunidades profesionales de aprendizaje\",\"Curr\u00edculo escolar\",\"escuela p\u00fablica\",\"Justicia social\",\"Pol\u00edticas educativas\"],\"articleSection\":[\"Por otra pol\u00edtica educativa. Foro de Sevilla\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/\",\"url\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/\",\"name\":\"La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2022\\\/04\\\/277591728_1177711622966687_2407132596885224980_n.jpg\",\"datePublished\":\"2022-04-18T05:00:59+00:00\",\"dateModified\":\"2024-08-21T14:50:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/#\\\/schema\\\/person\\\/4ee42898eb46b1f67fefe730f1a5209b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2022\\\/04\\\/277591728_1177711622966687_2407132596885224980_n.jpg\",\"contentUrl\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/2022\\\/04\\\/277591728_1177711622966687_2407132596885224980_n.jpg\",\"width\":1440,\"height\":1440,\"caption\":\"Ilustraci\u00f3n cedida por Joseba G. Plazuelo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/2022\\\/04\\\/18\\\/la-cornucopia-de-las-posibilidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La cornucopia de las posibilidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/#website\",\"url\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/\",\"name\":\"Por otra pol\u00edtica educativa. Foro de Sevilla.\",\"description\":\"Un blog de El Diario de la Educaci\u00f3n\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/#\\\/schema\\\/person\\\/4ee42898eb46b1f67fefe730f1a5209b\",\"name\":\"Antonio Lafuente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g\",\"caption\":\"Antonio Lafuente\"},\"url\":\"https:\\\/\\\/eldiariodelaeducacion.com\\\/porotrapoliticaeducativa\\\/author\\\/lafuente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/","og_locale":"es_ES","og_type":"article","og_title":"La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla","og_description":"Queremos acercar el mundo de la escuela a su entorno y tratamos de escuchar el murmullo de lo que se habla en la calle. Queremos dialogar con todo eso de lo que hablan los padres y las madres, los trabajadores y trabajadoras, y, en fin, los vecinos y vecinas. Nuestra convicci\u00f3n es que cuanto m\u00e1s nos acerquemos a lo que (nos) pasa, m\u00e1s f\u00e1cil ser\u00e1 captar la atenci\u00f3n de quienes participan.","og_url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/","og_site_name":"Por otra pol\u00edtica educativa. Foro de Sevilla.","article_published_time":"2022-04-18T05:00:59+00:00","article_modified_time":"2024-08-21T14:50:57+00:00","og_image":[{"width":1440,"height":1440,"url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg","type":"image\/jpeg"}],"author":"Antonio Lafuente","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Antonio Lafuente","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#article","isPartOf":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/"},"author":{"name":"Antonio Lafuente","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/#\/schema\/person\/4ee42898eb46b1f67fefe730f1a5209b"},"headline":"La cornucopia de las posibilidades","datePublished":"2022-04-18T05:00:59+00:00","dateModified":"2024-08-21T14:50:57+00:00","mainEntityOfPage":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/"},"wordCount":1717,"commentCount":0,"image":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#primaryimage"},"thumbnailUrl":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg","keywords":["Ciudadan\u00eda","ciudades educadoras","Comunidades profesionales de aprendizaje","Curr\u00edculo escolar","escuela p\u00fablica","Justicia social","Pol\u00edticas educativas"],"articleSection":["Por otra pol\u00edtica educativa. Foro de Sevilla"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/","url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/","name":"La cornucopia de las posibilidades - Por otra pol\u00edtica educativa. Foro de Sevilla.","isPartOf":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#primaryimage"},"image":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#primaryimage"},"thumbnailUrl":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg","datePublished":"2022-04-18T05:00:59+00:00","dateModified":"2024-08-21T14:50:57+00:00","author":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/#\/schema\/person\/4ee42898eb46b1f67fefe730f1a5209b"},"breadcrumb":{"@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#primaryimage","url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg","contentUrl":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-content\/uploads\/sites\/21\/2022\/04\/277591728_1177711622966687_2407132596885224980_n.jpg","width":1440,"height":1440,"caption":"Ilustraci\u00f3n cedida por Joseba G. Plazuelo"},{"@type":"BreadcrumbList","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/2022\/04\/18\/la-cornucopia-de-las-posibilidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/"},{"@type":"ListItem","position":2,"name":"La cornucopia de las posibilidades"}]},{"@type":"WebSite","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/#website","url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/","name":"Por otra pol\u00edtica educativa. Foro de Sevilla.","description":"Un blog de El Diario de la Educaci\u00f3n","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/#\/schema\/person\/4ee42898eb46b1f67fefe730f1a5209b","name":"Antonio Lafuente","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/12a21655cbc5583929349d42068a2981deee8f55cd2b5af0a7b58ee088d7220a?s=96&d=mm&r=g","caption":"Antonio Lafuente"},"url":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/author\/lafuente\/"}]}},"_links":{"self":[{"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/posts\/1434","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/users\/213"}],"replies":[{"embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/comments?post=1434"}],"version-history":[{"count":1,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/posts\/1434\/revisions"}],"predecessor-version":[{"id":2481,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/posts\/1434\/revisions\/2481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/media\/1438"}],"wp:attachment":[{"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/media?parent=1434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/categories?post=1434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/tags?post=1434"},{"taxonomy":"tipo","embeddable":true,"href":"https:\/\/eldiariodelaeducacion.com\/porotrapoliticaeducativa\/wp-json\/wp\/v2\/tipo?post=1434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}